{"id":410741,"date":"2019-07-08T13:52:50","date_gmt":"2019-07-08T11:52:50","guid":{"rendered":"https:\/\/askastrology.com\/sin-categorizar\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/"},"modified":"2019-07-08T13:52:50","modified_gmt":"2019-07-08T11:52:50","slug":"la-astrologia-africana-y-el-inicio-de-la-geomancia","status":"publish","type":"post","link":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/","title":{"rendered":"La astrolog\u00eda africana y el inicio de la geomancia"},"content":{"rendered":"<p><em>La astrolog\u00eda africana es la m\u00e1s primitiva de todas las astrolog\u00edas, ya que fueron los primeros en interesarse por las estrellas y sus movimientos.<br \/>\nFueron los primeros en idear la famosa t\u00e9cnica de la Geomancia.<br \/>\nLa geomancia es una t\u00e9cnica en la que se arrojan huesos al azar sobre una mesa, y se forma un signo o forma que luego se interpreta.<br \/>\nEste art\u00edculo ofrece una breve comprensi\u00f3n de lo que es la astrolog\u00eda africana a trav\u00e9s de sus signos.   <\/em><\/p>\n<h3>1. Padre &#8211; Baobab (<sup>4 de<\/sup> enero &#8211;<sup>3 de<\/sup> febrero)<\/h3>\n<p>  El \u00e1rbol baobab representa la naturaleza anciana de una persona.<br \/>\nAporta madurez y un sentimiento de orgullo por la propia naturaleza.<br \/>\nSu consideraci\u00f3n y honestidad al hablar es lo que les distingue.<br \/>\nLlevan un camino muy bien definido, ya que tienen sentido de la responsabilidad.<br \/>\nAunque muchas personas dependen de ellos, muestran una naturaleza independiente.<br \/>\nEl elemento de la Libertad puede observarse en la naturaleza.       <\/p>\n<h3>2. Madre &#8211; La riqueza del \u00e1mbar y la plata (<sup>4 de<\/sup> febrero &#8211;<sup>5 de<\/sup> marzo)<\/h3>\n<p>  El signo de la Madre muestra la firmeza de su personalidad.<br \/>\nTienen un profundo sentido de la moralidad y son virtuosos por naturaleza.<br \/>\nLas personas nacidas bajo este signo son met\u00f3dicas y organizadas.<br \/>\nLes gusta que todo est\u00e9 en orden y de acuerdo con el plan.<br \/>\nSu sed de aventura nunca est\u00e1 satisfecha, pero esto es lo que les hace seguir adelante sin que ning\u00fan obst\u00e1culo les detenga.<br \/>\nSu intelecto es su principal cualidad, que les ayuda en el pensamiento cr\u00edtico sobre muchas situaciones de la vida.       <\/p>\n<h3>3. Familia (<sup>6 de<\/sup> marzo &#8211;<sup>4 de<\/sup> abril)<\/h3>\n<p>  El signo de la familia representa a las personas desinteresadas.<br \/>\nNo tienen tiempo para ser ego\u00edstas o egoc\u00e9ntricos.<br \/>\nSon aquellas personas que trabajan \u00fanicamente para mejorar su sociedad y consiguen un cambio mejor en lo que hacen.<br \/>\nComparten una buena voluntad com\u00fan para el progreso de las personas.<br \/>\nLas personas \u00abfamiliares\u00bb tienen un destino definido de \u00e9xito y excelencia en todo aquello por lo que se esfuerzan.      <\/p>\n<h3>4. Peque\u00f1os Servicios al Vecindario (<sup>5 de<\/sup> abril &#8211;<sup>4 de<\/sup> mayo)<\/h3>\n<p>  Son los amigos de la astrolog\u00eda africana.<br \/>\nLas personas nacidas bajo este signo son despreocupadas y alegres por naturaleza.<br \/>\nSu personalidad brilla con un aura positiva.<br \/>\nDe este modo, pueden hacer amigos f\u00e1cilmente y destacar en las relaciones sociales.<br \/>\nEl problema, sin embargo, es que se encontrar\u00e1n en un momento de apuro que podr\u00edan evitar o favorecer las elecciones que deben hacer y las decisiones que deben tomar.<br \/>\nAparecer\u00e1 la nostalgia, pero el pensamiento cr\u00edtico ser\u00e1 importante en ese momento.       <\/p>\n<h3>5. El Mercado (<sup>5<\/sup> de mayo &#8211;<sup>4 de<\/sup> junio)<\/h3>\n<p>  Cada p\u00e1jaro tiene dos alas, para el ala de la paz y la armon\u00eda, est\u00e1n la brutalidad y el peligro.<br \/>\nTodas van juntas.<br \/>\nDel mismo modo, las personas nacidas bajo este signo tender\u00e1n a proporcionar paz y armon\u00eda a los dem\u00e1s y a mantenerlas tambi\u00e9n en sus vidas, pero como siempre hay calma antes de la tormenta.<br \/>\nEs probable que tambi\u00e9n se enfrenten a algunas fases malas.<br \/>\nLo importante es que no se rindan nunca, y seguro que saldr\u00e1n adelante.<br \/>\nLas personas de este signo no permanecen demasiado tiempo en una fase angustiosa si tienen una mente justa.       <\/p>\n<h3>6. El Antepasado (<sup>5 de<\/sup> junio &#8211;<sup>4 de<\/sup> julio)<\/h3>\n<p>  En la astrolog\u00eda africana, las personas nacidas bajo este signo suelen ser ego\u00edstas o tener un elemento narcisista en su personalidad.<br \/>\nEsto les hace muy egoc\u00e9ntricos, lo que a su vez es precursor del sentimiento de indiferencia por las emociones de la gente.<br \/>\nA veces pueden tomar un cariz oscuro, pero como su principal cualidad es gobernar y liderar, esto puede ayudarles en esa cuesti\u00f3n.<br \/>\nUn buen l\u00edder tiene sentimientos, pero a veces debe actuar sin ninguna influencia emocional.     <\/p>\n<h3>7. El Juez (<sup>5 de<\/sup> julio &#8211;<sup>4 de<\/sup> agosto)<\/h3>\n<p>  En la astrolog\u00eda africana, son las personas del respeto.<br \/>\nEl respeto es una cualidad virtuosa que es menos probable encontrar o mantener en la gente de hoy en d\u00eda.<br \/>\nLas personas nacidas bajo este signo siempre est\u00e1n abiertas a la cr\u00edtica y respetan profundamente los puntos de vista, opiniones y derechos de la gente.<br \/>\nSon el juez leg\u00edtimo.<br \/>\nLa apertura y el respeto son efectos de su naturaleza espiritual.      <\/p>\n<h3>8. La Nuez de Kola (<sup>5 de<\/sup> agosto &#8211;<sup>3 de<\/sup> septiembre)<\/h3>\n<p>  Las personas representadas por este signo suelen ser individuos hiperactivos a los que no les gustan los elementos aburridos en su vida.<br \/>\nLes gusta hacer cosas extraordinarias y disfrutar de la vida al m\u00e1ximo.<br \/>\nEsto va acompa\u00f1ado de su intelecto.<br \/>\nSon innatamente sabios, y su inteligencia se apodera de cualquier otra habilidad.     <\/p>\n<h3>9. El Viajero (<sup>4 de<\/sup> septiembre &#8211;<sup>3 de<\/sup> octubre)<\/h3>\n<p>  En la astrolog\u00eda africana, el signo de los viajeros significa el viaje de una persona tanto hacia el interior como hacia el exterior.<br \/>\nTienden a pensar profundamente sobre las preocupaciones de la vida y pueden consumirse por ellas con mayor frecuencia.<br \/>\nSin embargo, su capacidad de pensamiento profundo y su b\u00fasqueda de un significado eterno aportan un cierto valor a sus palabras, que son verdaderas hasta la m\u00e9dula.    <\/p>\n<h3>10. La distancia (<sup>4 de<\/sup> octubre &#8211;<sup>3 de<\/sup> noviembre)<\/h3>\n<p>  Son las personas m\u00e1s moralmente activas de la astrolog\u00eda africana.<br \/>\nTienden a no seguir las instituciones ya creadas, sino su propia voluntad e instintos.<br \/>\nSu curiosidad les lleva a una creatividad esencial.<br \/>\nPor eso tienen la cabeza llena de ideas originales y creativas.<br \/>\nEl problema, sin embargo, reside en su ansiedad, que es un gran obst\u00e1culo en su vida.<br \/>\nEst\u00e1n destinados al \u00e9xito si no es por la ansiedad.       <\/p>\n<h3>11. Ni\u00f1o del Mundo (<sup>4 de<\/sup> noviembre &#8211;<sup>3 de<\/sup> diciembre)<\/h3>\n<p>  Al igual que un ni\u00f1o con un aura en\u00e9rgica y positiva, siempre se alegran siendo optimistas.<br \/>\nSu sentido del orgullo a veces puede ser un lastre para ellos y hacerles da\u00f1o.<br \/>\nAun as\u00ed, las dificultades o incluso la depresi\u00f3n no les afectan m\u00e1s a menudo debido a su naturaleza bondadosa y generosa con la que lo afrontan.    <\/p>\n<h3>12. La cosecha y el granero (<sup>4 de<\/sup> diciembre &#8211;<sup>3 de<\/sup> enero)<\/h3>\n<p>  En la astrolog\u00eda africana, son los m\u00e1s virtuosos.<br \/>\nSuelen ser m\u00e1s productivos que los dem\u00e1s.<br \/>\nSu b\u00fasqueda de la felicidad y la soledad va en paralelo.<br \/>\nLa vida te traer\u00e1 muchas dificultades, pero la firmeza y el mantenerse firme pueden ayudarte a sobresalir en ella.<br \/>\nS\u00f3lo si pudieras confiar m\u00e1s a menudo en tu voluntad e instintos.<br \/>\nLa esencia de la astrolog\u00eda africana reside en la naturaleza serena de sus signos zodiacales, que desprende energ\u00eda positiva para cada signo.<br \/>\nLa tendencia se desprende claramente de las explicaciones anteriores.<br \/>\nPor tanto, se puede concluir que nos muestra una forma mejor de llevar nuestras vidas si se utiliza adecuadamente.       <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La astrolog\u00eda africana es la m\u00e1s primitiva de todas las astrolog\u00edas, ya que fueron los primeros en interesarse por las estrellas y sus movimientos. Fueron los primeros en idear la famosa t\u00e9cnica de la Geomancia. La geomancia es una t\u00e9cnica en la que se arrojan huesos al azar sobre una mesa, y se forma un [&hellip;]<\/p>\n","protected":false},"author":53,"featured_media":381342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"order-bump-settings":[],"_wpfnl_thankyou_order_overview":"on","_wpfnl_thankyou_order_details":"on","_wpfnl_thankyou_billing_details":"on","_wpfnl_thankyou_shipping_details":"on","footnotes":""},"categories":[16557],"tags":[],"class_list":["post-410741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-astrologia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La astrolog\u00eda africana y el inicio de la geomancia - askAstrology<\/title>\n<meta name=\"description\" content=\"El inicio de la astrolog\u00eda africana comenz\u00f3 con el comienzo de la antigua civilizaci\u00f3n africana. La t\u00e9cnica de la geomancia se cre\u00f3 en la Astrolog\u00eda. Sigue leyendo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La astrolog\u00eda africana y el inicio de la geomancia\" \/>\n<meta property=\"og:description\" content=\"La astrolog\u00eda africana es la m\u00e1s primitiva de todas las astrolog\u00edas, ya que fueron los primeros en interesarse por las estrellas y sus movimientos. Fueron\" \/>\n<meta property=\"og:url\" content=\"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/\" \/>\n<meta property=\"og:site_name\" content=\"askAstrology\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AskAstrologyOfficial\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-08T11:52:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/askastrology.com\/wp-content\/uploads\/2019\/07\/BL_AST_096_African_Astrology.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Morgan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AskAstrOfficial\" \/>\n<meta name=\"twitter:site\" content=\"@AskAstrOfficial\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Morgan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/astrologia\\\/la-astrologia-africana-y-el-inicio-de-la-geomancia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/astrologia\\\/la-astrologia-africana-y-el-inicio-de-la-geomancia\\\/\"},\"author\":{\"name\":\"Morgan\",\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/#\\\/schema\\\/person\\\/48212df6f5406b37c48106c605e0745d\"},\"headline\":\"La astrolog\u00eda africana y el inicio de la geomancia\",\"datePublished\":\"2019-07-08T11:52:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/astrologia\\\/la-astrologia-africana-y-el-inicio-de-la-geomancia\\\/\"},\"wordCount\":1153,\"publisher\":{\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/astrologia\\\/la-astrologia-africana-y-el-inicio-de-la-geomancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/askastrology.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/BL_AST_096_African_Astrology.jpg\",\"articleSection\":[\"Astrolog\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/astrologia\\\/la-astrologia-africana-y-el-inicio-de-la-geomancia\\\/\",\"url\":\"https:\\\/\\\/askastrology.com\\\/es\\\/astrologia\\\/la-astrologia-africana-y-el-inicio-de-la-geomancia\\\/\",\"name\":\"La astrolog\u00eda africana y el inicio de la geomancia - askAstrology\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/astrologia\\\/la-astrologia-africana-y-el-inicio-de-la-geomancia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/astrologia\\\/la-astrologia-africana-y-el-inicio-de-la-geomancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/askastrology.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/BL_AST_096_African_Astrology.jpg\",\"datePublished\":\"2019-07-08T11:52:50+00:00\",\"description\":\"El inicio de la astrolog\u00eda africana comenz\u00f3 con el comienzo de la antigua civilizaci\u00f3n africana. La t\u00e9cnica de la geomancia se cre\u00f3 en la Astrolog\u00eda. Sigue leyendo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/astrologia\\\/la-astrologia-africana-y-el-inicio-de-la-geomancia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/askastrology.com\\\/es\\\/astrologia\\\/la-astrologia-africana-y-el-inicio-de-la-geomancia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/astrologia\\\/la-astrologia-africana-y-el-inicio-de-la-geomancia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/askastrology.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/BL_AST_096_African_Astrology.jpg\",\"contentUrl\":\"https:\\\/\\\/askastrology.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/BL_AST_096_African_Astrology.jpg\",\"width\":1000,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/astrologia\\\/la-astrologia-africana-y-el-inicio-de-la-geomancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/askastrology.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Astrolog\u00eda\",\"item\":\"https:\\\/\\\/askastrology.com\\\/es\\\/blog\\\/astrologia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La astrolog\u00eda africana y el inicio de la geomancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/askastrology.com\\\/es\\\/\",\"name\":\"askAstrology\",\"description\":\"Astrology, Horoscope, Zodiac, Tarot, Numerology, Astrology\",\"publisher\":{\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/askastrology.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/#organization\",\"name\":\"askAstrology\",\"url\":\"https:\\\/\\\/askastrology.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/askastrology.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/new-logo-google.png\",\"contentUrl\":\"https:\\\/\\\/askastrology.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/new-logo-google.png\",\"width\":340,\"height\":268,\"caption\":\"askAstrology\"},\"image\":{\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AskAstrologyOfficial\\\/\",\"https:\\\/\\\/x.com\\\/AskAstrOfficial\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/askastrology\",\"https:\\\/\\\/www.pinterest.com\\\/askastrology\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/AskAstrology\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/askastrology.com\\\/es\\\/#\\\/schema\\\/person\\\/48212df6f5406b37c48106c605e0745d\",\"name\":\"Morgan\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a772722d60d00558fa62df2428c6e0d82a34124aca65f102cb8ed5c0974e93e3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a772722d60d00558fa62df2428c6e0d82a34124aca65f102cb8ed5c0974e93e3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a772722d60d00558fa62df2428c6e0d82a34124aca65f102cb8ed5c0974e93e3?s=96&d=mm&r=g\",\"caption\":\"Morgan\"},\"description\":\"I\u2019m Morgan \u2013 a passionate blog writer interested in various subjects linked with astrology, horoscopes, numerology, and lifestyle. I really enjoy digging up libraries and the internet to find useful, funny and enlightening topics to write about. Basically, I cannot stop reading and sharing food for thought. So, if reading my articles makes your day, it makes mine as well!\",\"url\":\"https:\\\/\\\/askastrology.com\\\/es\\\/author\\\/morgan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La astrolog\u00eda africana y el inicio de la geomancia - askAstrology","description":"El inicio de la astrolog\u00eda africana comenz\u00f3 con el comienzo de la antigua civilizaci\u00f3n africana. La t\u00e9cnica de la geomancia se cre\u00f3 en la Astrolog\u00eda. Sigue leyendo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/","og_locale":"es_ES","og_type":"article","og_title":"La astrolog\u00eda africana y el inicio de la geomancia","og_description":"La astrolog\u00eda africana es la m\u00e1s primitiva de todas las astrolog\u00edas, ya que fueron los primeros en interesarse por las estrellas y sus movimientos. Fueron","og_url":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/","og_site_name":"askAstrology","article_publisher":"https:\/\/www.facebook.com\/AskAstrologyOfficial\/","article_published_time":"2019-07-08T11:52:50+00:00","og_image":[{"width":1000,"height":630,"url":"https:\/\/askastrology.com\/wp-content\/uploads\/2019\/07\/BL_AST_096_African_Astrology.jpg","type":"image\/jpeg"}],"author":"Morgan","twitter_card":"summary_large_image","twitter_creator":"@AskAstrOfficial","twitter_site":"@AskAstrOfficial","twitter_misc":{"Escrito por":"Morgan","Tiempo de lectura":"6 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/#article","isPartOf":{"@id":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/"},"author":{"name":"Morgan","@id":"https:\/\/askastrology.com\/es\/#\/schema\/person\/48212df6f5406b37c48106c605e0745d"},"headline":"La astrolog\u00eda africana y el inicio de la geomancia","datePublished":"2019-07-08T11:52:50+00:00","mainEntityOfPage":{"@id":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/"},"wordCount":1153,"publisher":{"@id":"https:\/\/askastrology.com\/es\/#organization"},"image":{"@id":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/#primaryimage"},"thumbnailUrl":"https:\/\/askastrology.com\/wp-content\/uploads\/2019\/07\/BL_AST_096_African_Astrology.jpg","articleSection":["Astrolog\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/","url":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/","name":"La astrolog\u00eda africana y el inicio de la geomancia - askAstrology","isPartOf":{"@id":"https:\/\/askastrology.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/#primaryimage"},"image":{"@id":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/#primaryimage"},"thumbnailUrl":"https:\/\/askastrology.com\/wp-content\/uploads\/2019\/07\/BL_AST_096_African_Astrology.jpg","datePublished":"2019-07-08T11:52:50+00:00","description":"El inicio de la astrolog\u00eda africana comenz\u00f3 con el comienzo de la antigua civilizaci\u00f3n africana. La t\u00e9cnica de la geomancia se cre\u00f3 en la Astrolog\u00eda. Sigue leyendo","breadcrumb":{"@id":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/#primaryimage","url":"https:\/\/askastrology.com\/wp-content\/uploads\/2019\/07\/BL_AST_096_African_Astrology.jpg","contentUrl":"https:\/\/askastrology.com\/wp-content\/uploads\/2019\/07\/BL_AST_096_African_Astrology.jpg","width":1000,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/askastrology.com\/es\/astrologia\/la-astrologia-africana-y-el-inicio-de-la-geomancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/askastrology.com\/es\/"},{"@type":"ListItem","position":2,"name":"Astrolog\u00eda","item":"https:\/\/askastrology.com\/es\/blog\/astrologia\/"},{"@type":"ListItem","position":3,"name":"La astrolog\u00eda africana y el inicio de la geomancia"}]},{"@type":"WebSite","@id":"https:\/\/askastrology.com\/es\/#website","url":"https:\/\/askastrology.com\/es\/","name":"askAstrology","description":"Astrology, Horoscope, Zodiac, Tarot, Numerology, Astrology","publisher":{"@id":"https:\/\/askastrology.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/askastrology.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/askastrology.com\/es\/#organization","name":"askAstrology","url":"https:\/\/askastrology.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/askastrology.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/askastrology.com\/wp-content\/uploads\/2024\/02\/new-logo-google.png","contentUrl":"https:\/\/askastrology.com\/wp-content\/uploads\/2024\/02\/new-logo-google.png","width":340,"height":268,"caption":"askAstrology"},"image":{"@id":"https:\/\/askastrology.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AskAstrologyOfficial\/","https:\/\/x.com\/AskAstrOfficial","https:\/\/www.linkedin.com\/in\/askastrology","https:\/\/www.pinterest.com\/askastrology\/","https:\/\/www.youtube.com\/c\/AskAstrology"]},{"@type":"Person","@id":"https:\/\/askastrology.com\/es\/#\/schema\/person\/48212df6f5406b37c48106c605e0745d","name":"Morgan","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a772722d60d00558fa62df2428c6e0d82a34124aca65f102cb8ed5c0974e93e3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a772722d60d00558fa62df2428c6e0d82a34124aca65f102cb8ed5c0974e93e3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a772722d60d00558fa62df2428c6e0d82a34124aca65f102cb8ed5c0974e93e3?s=96&d=mm&r=g","caption":"Morgan"},"description":"I\u2019m Morgan \u2013 a passionate blog writer interested in various subjects linked with astrology, horoscopes, numerology, and lifestyle. I really enjoy digging up libraries and the internet to find useful, funny and enlightening topics to write about. Basically, I cannot stop reading and sharing food for thought. So, if reading my articles makes your day, it makes mine as well!","url":"https:\/\/askastrology.com\/es\/author\/morgan\/"}]}},"_links":{"self":[{"href":"https:\/\/askastrology.com\/es\/wp-json\/wp\/v2\/posts\/410741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/askastrology.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/askastrology.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/askastrology.com\/es\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/askastrology.com\/es\/wp-json\/wp\/v2\/comments?post=410741"}],"version-history":[{"count":0,"href":"https:\/\/askastrology.com\/es\/wp-json\/wp\/v2\/posts\/410741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/askastrology.com\/es\/wp-json\/wp\/v2\/media\/381342"}],"wp:attachment":[{"href":"https:\/\/askastrology.com\/es\/wp-json\/wp\/v2\/media?parent=410741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/askastrology.com\/es\/wp-json\/wp\/v2\/categories?post=410741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/askastrology.com\/es\/wp-json\/wp\/v2\/tags?post=410741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}